{"id":11600,"date":"2019-09-10T16:57:00","date_gmt":"2019-09-10T14:57:00","guid":{"rendered":"https:\/\/staging-corporate.shakazoola.com\/sem-categoria\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/"},"modified":"2023-04-06T14:38:06","modified_gmt":"2023-04-06T12:38:06","slug":"autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13","status":"publish","type":"post","link":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/","title":{"rendered":"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11600\" class=\"elementor elementor-11600 elementor-5117\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d3eb4be elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d3eb4be\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f419f4b\" data-id=\"3f419f4b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55eb2c25 elementor-widget elementor-widget-breadcrumbs\" data-id=\"55eb2c25\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/\">In\u00edcio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-500f68c5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"500f68c5\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63722f03\" data-id=\"63722f03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59d12bc elementor-widget elementor-widget-text-editor\" data-id=\"59d12bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t10 de Setembro, 2019\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f1ae556 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4f1ae556\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34de67d2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34de67d2\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d6427c0\" data-id=\"7d6427c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10becf91 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"10becf91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A IFRS, International Financial Reporting Standard (Norma Internacional de Relato Financeiro), estabelece normas internacionais de contabilidade para todos os grandes grupos, cotados ou n\u00e3o cotados em bolsa. Aplicam-se em mais de uma centena de pa\u00edses do mundo. Essas regras, que visam estabelecer um sistema contabil\u00edstico uniforme e transparente, foram muito refor\u00e7adas ap\u00f3s a crise financeira de 2008. Entre as medidas adotadas, a norma IFRS 13 foi publicada em 2011 para definir o princ\u00edpio do &#8220;justo valor&#8221; para um bem.<\/p>\n<p>Esse conceito \u00e9 primordial para o setor autom\u00f3vel. De facto, qualquer profissional com ve\u00edculos no seu balan\u00e7o deve ser capaz de os contabilizar pelo seu justo valor. Construtores, distribuidores, locadores de curto e longo prazo, seguradoras: todos os principais intervenientes no setor autom\u00f3vel est\u00e3o envolvidos.<\/p>\n<p>Desde sua cria\u00e7\u00e3o, em 2004, um dos principais objetivos da autobiz tem sido oferecer um valor justo para um ve\u00edculo, baseado-se em big data, machine learning e an\u00e1lise transparente do mercado na Internet.<\/p>\n<p>Foi nesta \u00f3tica que, a partir de 2017, a autobiz contratou a empresa Chappuis Halder para avaliar &#8220;o grau de fiabilidade, sinceridade, transpar\u00eancia e auditabilidade&#8221; da sua metodologia de avalia\u00e7\u00e3o.<\/p>\n<p>A an\u00e1lise desta empresa, l\u00edder em termos de conformidade com a IFRS, demonstrou a pertin\u00eancia e a efic\u00e1cia do m\u00e9todo. De facto, a Chappuis Halder confirma que as ferramentas de avalia\u00e7\u00e3o da autobiz respeitam a norma IFRS 13.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81db5bd elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"81db5bd\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-788650fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"788650fb\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-201dc308\" data-id=\"201dc308\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a875cc8 elementor-widget elementor-widget-text-editor\" data-id=\"4a875cc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A IFRS, International Financial Reporting Standard (Norma Internacional de Relato Financeiro), estabelece normas internacionais de contabilidade para todos os grandes grupos, cotados ou n\u00e3o cotados em bolsa. Aplicam-se em mais de uma centena de pa\u00edses do mundo. Essas regras, que visam estabelecer um sistema contabil\u00edstico uniforme e transparente, foram muito refor\u00e7adas ap\u00f3s a crise financeira de 2008. Entre as medidas adotadas, a norma IFRS 13 foi publicada em 2011 para definir o princ\u00edpio do &#8220;justo valor&#8221; para um bem<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e27d339 elementor-widget elementor-widget-heading\" data-id=\"2e27d339\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Em particular, esses especialistas observaram que: <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ee1e483 elementor-widget elementor-widget-text-editor\" data-id=\"7ee1e483\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Os modelos de avalia\u00e7\u00e3o da autobiz assentam numa base recorrente e peri\u00f3dica, fundada na recupera\u00e7\u00e3o dos pre\u00e7os de venda em sites especializados. A autobiz fornece, portanto, uma estimativa de pre\u00e7o de mercado que respeita o sentido das normas IFRS e a transpar\u00eancia necess\u00e1ria atrav\u00e9s dos dados explicativos para esse pre\u00e7o.<\/p>\n<p>A autobiz usa princ\u00edpios matem\u00e1ticos, bem como t\u00e9cnicas de Machine Learning para estimar de forma mais justa os pre\u00e7os dos ve\u00edculos, ao valor atual.<\/p>\n<p>Finalmente, o m\u00e9todo de avalia\u00e7\u00e3o da autobiz apoia-se numa base de dados de mais de 10 mil milh\u00f5es de pre\u00e7os listados, permitindo a acuidade e a precis\u00e3o exigidas pelas normas internacionais de contabilidade.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-304305be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"304305be\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-37ba6728\" data-id=\"37ba6728\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3892cb95 elementor-widget elementor-widget-image\" data-id=\"3892cb95\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1505\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-660ea4d9\" data-id=\"660ea4d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ae9cc29 elementor-widget elementor-widget-text-editor\" data-id=\"5ae9cc29\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Emmanuel Labi, Diretor-Geral da autobiz, refere:<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5060978 elementor-widget elementor-widget-text-editor\" data-id=\"5060978\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ser hoje a \u00fanica ferramenta de avalia\u00e7\u00e3o compat\u00edvel com o IFRS13 \u00e9 o reconhecimento da qualidade do trabalho di\u00e1rio das mais de 40 pessoas que comp\u00f5em as nossas equipas de Big Data e Algoritmia. Essa conformidade com as normas tamb\u00e9m \u00e9 para n\u00f3s um elemento essencial nas nossas parcerias com os nossos clientes de grandes contas, que apoiamos em 23 pa\u00edses da Europa.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bb0721 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bb0721\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-36be575a\" data-id=\"36be575a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7011ed08 elementor-widget elementor-widget-shortcode\" data-id=\"7011ed08\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4209\" class=\"elementor elementor-4209 elementor-2712 elementor-2712\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8faa43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8faa43\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d56921c\" data-id=\"d56921c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f76613 elementor-widget elementor-widget-heading\" data-id=\"3f76613\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sobre o autobiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbc700 elementor-widget elementor-widget-text-editor\" data-id=\"2bbc700\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde 2004, a Autobiz acompanha todos os intervenientes da ind\u00fastria autom\u00f3vel europeia com solu\u00e7\u00f5es de recupera\u00e7\u00e3o e de comercializa\u00e7\u00e3o. Este apoio baseia-se em 20 anos de hist\u00f3rico de dados e na experi\u00eancia da web, software empresarial dos 280 empregados da empresa. Hoje baseada em La D\u00e9fense (Fran\u00e7a), a autobiz tamb\u00e9m tem escrit\u00f3rios em Berlim, Val\u00eancia (Espanha) e Mil\u00e3o. A autobiz apoia mais de 20 l\u00edderes na revenda de autom\u00f3veis usados (fabricantes, bancos, leasers, leiloeiros, etc.) assim como 5.000 pontos de venda em 22 pa\u00edses da Europa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e866364 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e866364\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5a5277\" data-id=\"e5a5277\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-024f141 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"024f141\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e51e963 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e51e963\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9a263e\" data-id=\"e9a263e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8f7976 elementor-widget elementor-widget-heading\" data-id=\"b8f7976\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leia tamb\u00e9m...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40755c2 communique-carousel overflow-h elementor-widget elementor-widget-jet-posts\" data-id=\"40755c2\" data-element_type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3,&quot;slides_to_scroll&quot;:&quot;1&quot;}\" data-widget_type=\"jet-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-posts jet-elements\"><div class=\"jet-carousel elementor-slick-slider\" data-slider_options=\"{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;.jet-posts__prev-arrow-40755c2&quot;,&quot;nextArrow&quot;:&quot;.jet-posts__next-arrow-40755c2&quot;,&quot;rtl&quot;:false}\" dir=\"ltr\"><div class=\"jet-posts col-row  jet-equal-cols\"><div class=\"jet-posts__prev-arrow-40755c2 jet-arrow prev-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><\/div><div class=\"jet-posts__next-arrow-40755c2 jet-arrow next-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><\/div><div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/a-autobiz-expande-as-suas-operacoes-de-valor-residual-na-iberia\/\" target=\"\">A autobiz expande as suas opera\u00e7\u00f5es de Valor Residual na Ib\u00e9ria<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/2026\/07\/15\/\"  class=\"post__date-link\" ><time datetime=\"2026-07-15T14:50:03+02:00\" title=\"2026-07-15T14:50:03+02:00\">15 de Julho, 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">A autobiz anuncia a expans\u00e3o das suas atividades de Valor Residual e Financiamento Autom\u00f3vel na Pen\u00ednsula Ib\u00e9rica com a disponibiliza\u00e7\u00e3o&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/a-autobiz-expande-as-suas-operacoes-de-valor-residual-na-iberia\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Leia mais<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-apresenta-uma-nova-abordagem-de-avaliacao-b2b-de-veiculos-orientada-pelo-mercado\/\" target=\"\">autobiz apresenta uma nova abordagem de avalia\u00e7\u00e3o B2B de ve\u00edculos orientada pelo mercado<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/2026\/06\/29\/\"  class=\"post__date-link\" ><time datetime=\"2026-06-29T12:41:59+02:00\" title=\"2026-06-29T12:41:59+02:00\">29 de Junho, 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">Num mercado de ve\u00edculos usados atualmente marcado por oscila\u00e7\u00f5es s\u00fabitas nos valores de revenda profissional, perturba\u00e7\u00f5es geopol\u00edticas e altera\u00e7\u00f5es r\u00e1pidas&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-apresenta-uma-nova-abordagem-de-avaliacao-b2b-de-veiculos-orientada-pelo-mercado\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Leia mais<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/a-point-s-escolheu-a-autobizmarket-para-equipar-toda-a-sua-rede-de-vendas-de-automoveis\/\" target=\"\">A Point S escolheu a autobizMarket para equipar toda a sua rede de vendas de autom\u00f3veis<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/2026\/04\/20\/\"  class=\"post__date-link\" ><time datetime=\"2026-04-20T17:01:24+02:00\" title=\"2026-04-20T17:01:24+02:00\">20 de Abril, 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">A autobiz, l\u00edder europeia em solu\u00e7\u00f5es de avalia\u00e7\u00e3o e dados autom\u00f3veis para profissionais, anuncia a assinatura de uma parceria estrat\u00e9gica&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/a-point-s-escolheu-a-autobizmarket-para-equipar-toda-a-sua-rede-de-vendas-de-automoveis\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Leia mais<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-and-jato-dynamics-forge-strategic-european-partnership-to-redefine-vehicle-identification-and-valuation-standards\/\" target=\"\">A autobiz e a JATO Dynamics firmam parceria estrat\u00e9gica europeia para redefinir os padr\u00f5es de identifica\u00e7\u00e3o e avalia\u00e7\u00e3o de ve\u00edculos<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/2026\/03\/31\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-31T10:05:25+02:00\" title=\"2026-03-31T10:05:25+02:00\">31 de Mar\u00e7o, 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">A autobiz, l\u00edder europeia em avalia\u00e7\u00e3o de ve\u00edculos usados \u200b\u200be intelig\u00eancia de valor residual, e a JATO Dynamics, l\u00edder global&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-and-jato-dynamics-forge-strategic-european-partnership-to-redefine-vehicle-identification-and-valuation-standards\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Leia mais<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobizmarket-the-newest-version-of-the-local-best-market-valuation-tool-is-now-available-in-portugal-evolving-to-better-meet-users-needs\/\" target=\"\">Melhor ferramenta de avalia\u00e7\u00e3o do mercado, o autobizMarket est\u00e1 a evoluir para responder de forma ainda mais precisa \u00e0s necessidades dos seus utilizadores<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/2025\/10\/27\/\"  class=\"post__date-link\" ><time datetime=\"2025-10-27T09:05:32+01:00\" title=\"2025-10-27T09:05:32+01:00\">27 de Outubro, 2025<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz announces a major investment in R&amp;D to upgrade autobizMarket, one of the flagship solutions within the autobizOffice suite. The&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobizmarket-the-newest-version-of-the-local-best-market-valuation-tool-is-now-available-in-portugal-evolving-to-better-meet-users-needs\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Leia mais<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/en-cours-de-test-avance-chez-stellantis-carcheck-ai-promet-de-faire-gagner-jusqua-3-semaines-lors-du-defleet-dun-vehicule-2\/\" target=\"\">Atualmente em testes avan\u00e7ados na Stellantis, o Carcheck.AI promete economizar at\u00e9 3 semanas durante o \"Defleet\" de um ve\u00edculo<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/2025\/10\/21\/\"  class=\"post__date-link\" ><time datetime=\"2025-10-21T09:00:00+02:00\" title=\"2025-10-21T09:00:00+02:00\">21 de Outubro, 2025<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">A autobiz est\u00e1 dando um novo passo em dire\u00e7\u00e3o \u00e0 inspe\u00e7\u00e3o automatizada e \u00e0 digitaliza\u00e7\u00e3o do remarketing. Baseada na solu\u00e7\u00e3o&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/en-cours-de-test-avance-chez-stellantis-carcheck-ai-promet-de-faire-gagner-jusqua-3-semaines-lors-du-defleet-dun-vehicule-2\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Leia mais<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bde37e8 elementor-align-center elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"bde37e8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corporate.autobiz.com\/nos-actualites\/nos-communiques\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Todos os nossos comunicados de imprensa<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo. Ap\u00f3s uma auditoria especializada, a autobiz afirma-se como a primeira empresa de avalia\u00e7\u00e3o a respeitar a norma IFRS13.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-11600","post","type-post","status-publish","format-standard","hentry","category-comunicado-de-imprensa-pt-pt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13<\/title>\n<meta name=\"description\" content=\"Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13\" \/>\n<meta property=\"og:description\" content=\"Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/\" \/>\n<meta property=\"og:site_name\" content=\"autobiz Corporate\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-10T14:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T12:38:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" \/>\n<meta name=\"author\" content=\"solene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"solene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/\"},\"author\":{\"name\":\"solene\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\"},\"headline\":\"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13\",\"datePublished\":\"2019-09-10T14:57:00+00:00\",\"dateModified\":\"2023-04-06T12:38:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/\"},\"wordCount\":539,\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"articleSection\":[\"Comunicado de imprensa\"],\"inLanguage\":\"pt-PT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/\",\"name\":\"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"datePublished\":\"2019-09-10T14:57:00+00:00\",\"dateModified\":\"2023-04-06T12:38:06+00:00\",\"description\":\"Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/comunicado-de-imprensa-pt-pt\\\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de imprensa\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/category\\\/comunicado-de-imprensa-pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/\",\"name\":\"autobiz Corporate\",\"description\":\"Leader europ\u00e9en de la cotation automobile et de la reprise\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#organization\",\"name\":\"autobiz Corporate\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"width\":320,\"height\":76,\"caption\":\"autobiz Corporate\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\",\"name\":\"solene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"caption\":\"solene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13","description":"Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/","og_locale":"pt_PT","og_type":"article","og_title":"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13","og_description":"Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo.","og_url":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/","og_site_name":"autobiz Corporate","article_published_time":"2019-09-10T14:57:00+00:00","article_modified_time":"2023-04-06T12:38:06+00:00","og_image":[{"url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","type":"","width":"","height":""}],"author":"solene","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"solene","Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#article","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/"},"author":{"name":"solene","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6"},"headline":"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13","datePublished":"2019-09-10T14:57:00+00:00","dateModified":"2023-04-06T12:38:06+00:00","mainEntityOfPage":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/"},"wordCount":539,"publisher":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","articleSection":["Comunicado de imprensa"],"inLanguage":"pt-PT"},{"@type":"WebPage","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/","url":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/","name":"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#primaryimage"},"image":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","datePublished":"2019-09-10T14:57:00+00:00","dateModified":"2023-04-06T12:38:06+00:00","description":"Ap\u00f3s a crise financeira de 2008, as normas financeiras internacionais foram refor\u00e7adas, particularmente para a avalia\u00e7\u00e3o dos stocks de ve\u00edculos de construtores e locadores de curto e longo prazo.","breadcrumb":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#primaryimage","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/comunicado-de-imprensa-pt-pt\/autobiz-primeira-empresa-de-avaliacao-compativel-com-as-normas-ifrs13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/corporate.autobiz.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Comunicado de imprensa","item":"https:\/\/corporate.autobiz.com\/pt-pt\/category\/comunicado-de-imprensa-pt-pt\/"},{"@type":"ListItem","position":3,"name":"autobiz: primeira empresa de avalia\u00e7\u00e3o compat\u00edvel com as normas IFRS13"}]},{"@type":"WebSite","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#website","url":"https:\/\/corporate.autobiz.com\/pt-pt\/","name":"autobiz Corporate","description":"Leader europ\u00e9en de la cotation automobile et de la reprise","publisher":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporate.autobiz.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#organization","name":"autobiz Corporate","url":"https:\/\/corporate.autobiz.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","width":320,"height":76,"caption":"autobiz Corporate"},"image":{"@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/corporate.autobiz.com\/pt-pt\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6","name":"solene","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","caption":"solene"}}]}},"_links":{"self":[{"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/posts\/11600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=11600"}],"version-history":[{"count":0,"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/posts\/11600\/revisions"}],"wp:attachment":[{"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=11600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=11600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=11600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}