{"id":7969,"date":"2023-01-17T09:40:31","date_gmt":"2023-01-17T08:40:31","guid":{"rendered":"https:\/\/staging-corporate.shakazoola.com\/?p=7969"},"modified":"2023-03-30T14:36:11","modified_gmt":"2023-03-30T12:36:11","slug":"smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei","status":"publish","type":"post","link":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/","title":{"rendered":"smart Europe sceglie autobiz per l\u2019attivit\u00e0 di permuta nei suoi principali mercati europei"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7969\" class=\"elementor elementor-7969 elementor-7959\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46926cee elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46926cee\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-193c1c7d\" data-id=\"193c1c7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ac9262 elementor-widget elementor-widget-breadcrumbs\" data-id=\"77ac9262\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/corporate.autobiz.com\/it\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7feb77ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7feb77ad\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b7bfe31\" data-id=\"3b7bfe31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7d3005 elementor-widget elementor-widget-text-editor\" data-id=\"e7d3005\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t17 Gennaio 2023\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf708b3 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"cf708b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">smart Europe sceglie autobiz per l\u2019attivit\u00e0 di permuta nei suoi principali mercati europei<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-15675540 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"15675540\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-204611da\" data-id=\"204611da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be0d129 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"be0d129\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li style=\"text-align: left;\">autobiz accompagna gli ambiziosi piani di sviluppo di smart Europe nei suoi principali mercati europei.<\/li>\n<li style=\"text-align: left;\">Nello specifico, autobiz fornir\u00e0 ai siti di smart Europe alcuni strumenti di valutazione online&#8230;<\/li>\n<li style=\"text-align: left;\">\u2026nel contempo garantendo ai partner di smart Europe un prezzo di acquisto nel punto vendita tramite la suite di autobizOffice.<\/li>\n<li style=\"text-align: left;\">Questa partnership si inserisce nella strategia di distribuzione omnichannel di smart Europe, fondata su un\u2019integrazione trasparente tra un percorso di acquisto online completo e un\u2019eccellente esperienza di acquisto fisica presso la rete di agenti di nuova costituzione.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-762ec7c0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"762ec7c0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2175229b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2175229b\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-28e5151d\" data-id=\"28e5151d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-240c091 elementor-widget elementor-widget-text-editor\" data-id=\"240c091\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>smart Europe lancia la sua nuovissima gamma di modelli puramente elettrici che si espander\u00e0 poi in ulteriori segmenti nei prossimi anni. Questi nuovi modelli sono associati a una customer journey online e offline completamente integrata, che \u00e8 supportata da una rinnovata rete di agenti distribuiti in Europa, stabilita attraverso partners accuratamente selezionati.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e4cc6d elementor-widget elementor-widget-heading\" data-id=\"51e4cc6d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nuovo modello di agenzia supportato da funzionalit\u00e0 avanzate di permuta e remarketing<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c64127f elementor-widget elementor-widget-text-editor\" data-id=\"c64127f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nel contesto di attuazione del new retail model &#8211; che implementa un modello di <em>\u201cgenuine agents\u201d<\/em> nei suoi principali mercati &#8211; smart Europe supporter\u00e0 la sua rete con processi di permuta e remarketing, attraverso soluzioni complete fornite da autobiz. Nei principali paesi europei di smart i futuri<em> \u201cgenuine agents\u201d<\/em> beneficeranno inoltre di offerte di permuta garantita nel punto vendita.<\/p>\n<p>Come accennato, questo servizio basato sulla suite autobizOffice, consentir\u00e0 ai <em>\u201cgenuine agents\u201d<\/em> di smart Europe di utilizzare la soluzione <strong>autobizCarcheck<\/strong> per ispezionare i veicoli, e quindi di richiedere un prezzo garantito che utilizzer\u00e0:<\/p>\n<ul>\n<li>la soluzione <strong>autobizAI<\/strong> per il riconoscimento dei danni alla carrozzeria<\/li>\n<li><strong>autobizMarket<\/strong> per il calcolo del valore di mercato e di permuta<\/li>\n<li>la piattaforma <strong>autobizTrade<\/strong> per la rivendita B2B dei veicoli.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e2891d8 elementor-widget elementor-widget-heading\" data-id=\"5e2891d8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Moduli di permuta autobiz sui siti web di smart Europe nei principali paesi europei<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d7eaa80 elementor-widget elementor-widget-text-editor\" data-id=\"6d7eaa80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oltre ai servizi offline, autobiz e smart Europe hanno recentemente siglato un accordo in base al quale i siti web di smart Europe rivolti ai clienti forniranno una valutazione online per la permuta dei veicoli, basata sui dati e le tecnologie di autobiz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1aeae9c6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aeae9c6\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-659eea10\" data-id=\"659eea10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ddb170 elementor-widget elementor-widget-image\" data-id=\"77ddb170\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1504\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce3e6d2\" data-id=\"ce3e6d2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70d78d8c elementor-widget elementor-widget-text-editor\" data-id=\"70d78d8c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>smart Europe \u00e8 orgogliosa di estendere la sua partnership con autobiz, fornitore principale di strumenti di valutazione dei veicoli, permuta e remarketing. Le loro solide e mature tecnologie di raccolta ed elaborazione dei dati ci aiuteranno a offrire un&#8217;esperienza di permuta online e offline di qualit\u00e0 superiore, non solo per i nostri clienti, ma anche per l&#8217;intera rete. L&#8217;innovazione \u00e8 al centro di entrambe le nostre aziende, ed \u00e8 ci\u00f2 che ci aspettiamo da questa collaborazione.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21be2eb1 elementor-widget elementor-widget-text-editor\" data-id=\"21be2eb1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Andr\u00e9 Janssen-Timmen, Sales Director e Chief Operating Officer di smart Europe GmbH.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a5e7b9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a5e7b9a\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ceec81\" data-id=\"8ceec81\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c64ae2 elementor-widget elementor-widget-image\" data-id=\"3c64ae2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1504\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-abaefc3\" data-id=\"abaefc3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fe9fbf elementor-widget elementor-widget-text-editor\" data-id=\"6fe9fbf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo molto onorati di poter accompagnare smart Europe nel suo ambizioso e innovativo progetto di permuta. Questo ci motiva inoltre a spingere ulteriormente sull&#8217;innovazione, per continuare a migliorare i processi di permuta e remarketing sia online che offline dei nostri clienti OEM.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f8b457 elementor-widget elementor-widget-text-editor\" data-id=\"7f8b457\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Emmanuel Labi, Presidente di autobiz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51f1c220 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51f1c220\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ea8f124\" data-id=\"2ea8f124\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddab0ff elementor-widget elementor-widget-shortcode\" data-id=\"ddab0ff\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4208\" class=\"elementor elementor-4208 elementor-2712 elementor-2712\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8faa43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8faa43\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d56921c\" data-id=\"d56921c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f76613 elementor-widget elementor-widget-heading\" data-id=\"3f76613\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">A proposito di autobiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbc700 elementor-widget elementor-widget-text-editor\" data-id=\"2bbc700\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 2004, autobiz supporta tutti gli attori europei dell&#8217;industria automobilistica con soluzioni di valutazione e permuta. Questo supporto si basa su 20 anni di cronologia dei dati, sul know-how web, sul software e sull&#8217;esperienza dei 280 dipendenti dell&#8217;azienda. autobiz \u00e8 basata a La D\u00e9fense (Parigi) e ha anche uffici a Berlino, Valencia (Spagna) e Milano. L\u2019azienda supporta pi\u00f9 di 20 leader nel mercato dell&#8217;usato (costruttori, banche, aziende di leasing, case d\u2019asta\u2026) e 5.000 punti vendita in 22 paesi in tutta Europa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e866364 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e866364\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5a5277\" data-id=\"e5a5277\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-024f141 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"024f141\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e51e963 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e51e963\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9a263e\" data-id=\"e9a263e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8f7976 elementor-widget elementor-widget-heading\" data-id=\"b8f7976\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leggi anche...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40755c2 communique-carousel overflow-h elementor-widget elementor-widget-jet-posts\" data-id=\"40755c2\" data-element_type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3,&quot;slides_to_scroll&quot;:&quot;1&quot;}\" data-widget_type=\"jet-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-posts jet-elements\"><div class=\"jet-carousel elementor-slick-slider\" data-slider_options=\"{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;.jet-posts__prev-arrow-40755c2&quot;,&quot;nextArrow&quot;:&quot;.jet-posts__next-arrow-40755c2&quot;,&quot;rtl&quot;:false}\" dir=\"ltr\"><div class=\"jet-posts col-row  jet-equal-cols\"><div class=\"jet-posts__prev-arrow-40755c2 jet-arrow prev-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><\/div><div class=\"jet-posts__next-arrow-40755c2 jet-arrow next-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><\/div><div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-introduce-un-nuovo-approccio-basato-sul-mercato-alla-valutazione-b2b-dei-veicoli\/\" target=\"\">autobiz introduce un nuovo approccio basato sul mercato alla valutazione B2B dei veicoli<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/06\/29\/\"  class=\"post__date-link\" ><time datetime=\"2026-06-29T12:41:59+02:00\" title=\"2026-06-29T12:41:59+02:00\">29 Giugno 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">In un mercato dell\u2019usato sempre pi\u00f9 influenzato da improvvise variazioni dei valori B2B,tensioni geopolitiche e cambiamenti rapidi della domanda, gli&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-introduce-un-nuovo-approccio-basato-sul-mercato-alla-valutazione-b2b-dei-veicoli\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/trasparenza-che-genera-fiducia-il-nuovo-standard-per-le-valutazioni-dellusato\/\" target=\"\">Trasparenza che genera fiducia - il nuovo standard per le valutazioni dell\u2019usato<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/05\/29\/\"  class=\"post__date-link\" ><time datetime=\"2026-05-29T12:40:51+02:00\" title=\"2026-05-29T12:40:51+02:00\">29 Maggio 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">In un mercato automotive sempre pi\u00f9 competitivo e guidato dalla fiducia del consumatore, il tema della trasparenza sta assumendo un&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/trasparenza-che-genera-fiducia-il-nuovo-standard-per-le-valutazioni-dellusato\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/point-s-chooses-autobizmarket-to-equip-its-entire-car-sales-network-it\/\" target=\"\">Point S sceglie autobizMarket per dotare la propria rete di vendita auto<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/04\/20\/\"  class=\"post__date-link\" ><time datetime=\"2026-04-20T17:01:24+02:00\" title=\"2026-04-20T17:01:24+02:00\">20 Aprile 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz, leader europeo nella valutazione di veicoli e nelle soluzioni basate sui dati per i professionisti del settore, annuncia la&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/point-s-chooses-autobizmarket-to-equip-its-entire-car-sales-network-it\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-e-jato-dynamics-stringono-una-partnership-strategica-europea-per-ridefinire-gli-standard-di-identificazione-e-valutazione-dei-veicoli\/\" target=\"\">autobiz e JATO Dynamics stringono una partnership strategica europea per ridefinire gli standard di identificazione e valutazione dei veicoli.<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/03\/26\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-26T10:00:54+01:00\" title=\"2026-03-26T10:00:54+01:00\">26 Marzo 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz &#8211; leader europeo nella valutazione dei veicoli usati e nell\u2019analisi sul valore residuo &#8211; e JATO Dynamics &#8211; leader&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-e-jato-dynamics-stringono-una-partnership-strategica-europea-per-ridefinire-gli-standard-di-identificazione-e-valutazione-dei-veicoli\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-italia-premiata-da-great-place-to-work-italia-come-best-workplace-2026\/\" target=\"\">autobiz Italia \u00e8 stata premiata da Great Place To Work\u00ae Italia come una delle migliori aziende italiane per cui lavorare, all\u2019interno della Classifica Best Workplaces\u2122 2026<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/03\/25\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-25T10:21:55+01:00\" title=\"2026-03-25T10:21:55+01:00\">25 Marzo 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz Italia \u00e8 stata valutata dai collaboratori dell\u2019azienda attraverso un\u2019indagine sul clima interno. Il risultato: grande soddisfazione da parte dei&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-italia-premiata-da-great-place-to-work-italia-come-best-workplace-2026\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nuova-versione-di-autobizmarket-lanciata-in-italia\/\" target=\"\">La nuova versione di autobizMarket \u00e8 stata lanciata in Italia con un'interfaccia riprogettata e nuove funzionalit\u00e0<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/03\/12\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-12T08:00:04+01:00\" title=\"2026-03-12T08:00:04+01:00\">12 Marzo 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz annuncia il lancio della nuova versione di autobizMarket, la soluzione di punta per la valutazione dei veicoli usati all\u2019interno&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nuova-versione-di-autobizmarket-lanciata-in-italia\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bde37e8 elementor-align-center elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"bde37e8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corporate.autobiz.com\/it\/comunicati\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tutti i nostri comunicati<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>autobiz accompagna gli ambiziosi piani di sviluppo di smart Europe nei suoi principali mercati europei. Nello specifico, autobiz fornir\u00e0 ai siti di smart Europe alcuni strumenti di valutazione online&#8230; \u2026nel contempo garantendo ai partner di smart Europe un prezzo di acquisto nel punto vendita tramite la suite di autobizOffice. Questa partnership si inserisce nella strategia [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-7969","post","type-post","status-publish","format-standard","hentry","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>smart Europe sceglie autobiz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"smart Europe sceglie autobiz\" \/>\n<meta property=\"og:description\" content=\"autobiz accompagna gli ambiziosi piani di sviluppo di smart Europe nei suoi principali mercati europei. Nello specifico, autobiz fornir\u00e0 ai siti di smart Europe alcuni strumenti di valutazione online&#8230; \u2026nel contempo garantendo ai partner di smart Europe un prezzo di acquisto nel punto vendita tramite la suite di autobizOffice. Questa partnership si inserisce nella strategia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/\" \/>\n<meta property=\"og:site_name\" content=\"autobiz Corporate\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-17T08:40:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-30T12:36:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" \/>\n<meta name=\"author\" content=\"solene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"solene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/\"},\"author\":{\"name\":\"solene\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\"},\"headline\":\"smart Europe sceglie autobiz per l\u2019attivit\u00e0 di permuta nei suoi principali mercati europei\",\"datePublished\":\"2023-01-17T08:40:31+00:00\",\"dateModified\":\"2023-03-30T12:36:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/\"},\"wordCount\":479,\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/\",\"name\":\"smart Europe sceglie autobiz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"datePublished\":\"2023-01-17T08:40:31+00:00\",\"dateModified\":\"2023-03-30T12:36:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicato stampa\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/category\\\/comunicato-stampa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"smart Europe sceglie autobiz per l\u2019attivit\u00e0 di permuta nei suoi principali mercati europei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/\",\"name\":\"autobiz Corporate\",\"description\":\"Leader europ\u00e9en de la cotation automobile et de la reprise\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#organization\",\"name\":\"autobiz Corporate\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"width\":320,\"height\":76,\"caption\":\"autobiz Corporate\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\",\"name\":\"solene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"caption\":\"solene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"smart Europe sceglie autobiz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/","og_locale":"it_IT","og_type":"article","og_title":"smart Europe sceglie autobiz","og_description":"autobiz accompagna gli ambiziosi piani di sviluppo di smart Europe nei suoi principali mercati europei. Nello specifico, autobiz fornir\u00e0 ai siti di smart Europe alcuni strumenti di valutazione online&#8230; \u2026nel contempo garantendo ai partner di smart Europe un prezzo di acquisto nel punto vendita tramite la suite di autobizOffice. Questa partnership si inserisce nella strategia [&hellip;]","og_url":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/","og_site_name":"autobiz Corporate","article_published_time":"2023-01-17T08:40:31+00:00","article_modified_time":"2023-03-30T12:36:11+00:00","og_image":[{"url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","type":"","width":"","height":""}],"author":"solene","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"solene","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#article","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/"},"author":{"name":"solene","@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6"},"headline":"smart Europe sceglie autobiz per l\u2019attivit\u00e0 di permuta nei suoi principali mercati europei","datePublished":"2023-01-17T08:40:31+00:00","dateModified":"2023-03-30T12:36:11+00:00","mainEntityOfPage":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/"},"wordCount":479,"publisher":{"@id":"https:\/\/corporate.autobiz.com\/it\/#organization"},"image":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/","url":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/","name":"smart Europe sceglie autobiz","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#primaryimage"},"image":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","datePublished":"2023-01-17T08:40:31+00:00","dateModified":"2023-03-30T12:36:11+00:00","breadcrumb":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#primaryimage","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/smart-europe-sceglie-autobiz-per-lattivita-di-permuta-nei-suoi-principali-mercati-europei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporate.autobiz.com\/it\/"},{"@type":"ListItem","position":2,"name":"Comunicato stampa","item":"https:\/\/corporate.autobiz.com\/it\/category\/comunicato-stampa\/"},{"@type":"ListItem","position":3,"name":"smart Europe sceglie autobiz per l\u2019attivit\u00e0 di permuta nei suoi principali mercati europei"}]},{"@type":"WebSite","@id":"https:\/\/corporate.autobiz.com\/it\/#website","url":"https:\/\/corporate.autobiz.com\/it\/","name":"autobiz Corporate","description":"Leader europ\u00e9en de la cotation automobile et de la reprise","publisher":{"@id":"https:\/\/corporate.autobiz.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporate.autobiz.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/corporate.autobiz.com\/it\/#organization","name":"autobiz Corporate","url":"https:\/\/corporate.autobiz.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","width":320,"height":76,"caption":"autobiz Corporate"},"image":{"@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6","name":"solene","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","caption":"solene"}}]}},"_links":{"self":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/posts\/7969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/comments?post=7969"}],"version-history":[{"count":0,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/posts\/7969\/revisions"}],"wp:attachment":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/media?parent=7969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/categories?post=7969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/tags?post=7969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}