{"id":5770,"date":"2020-12-09T16:44:00","date_gmt":"2020-12-09T15:44:00","guid":{"rendered":"https:\/\/staging-corporate.shakazoola.com\/non-categorizzato\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/"},"modified":"2022-11-16T11:07:32","modified_gmt":"2022-11-16T10:07:32","slug":"nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo","status":"publish","type":"post","link":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/","title":{"rendered":"Nissan e autobiz firmano una collaborazione inedita a livello europeo"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5770\" class=\"elementor elementor-5770 elementor-5090\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-35513a74 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"35513a74\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb32973\" data-id=\"cb32973\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-234afeb1 elementor-widget elementor-widget-breadcrumbs\" data-id=\"234afeb1\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/corporate.autobiz.com\/it\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ebb060c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ebb060c\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-488afe8d\" data-id=\"488afe8d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e272fd8 elementor-widget elementor-widget-text-editor\" data-id=\"6e272fd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t9 Dicembre 2020\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-106c2ad0 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"106c2ad0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nissan e autobiz firmano una collaborazione inedita a livello europeo<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-387dfc6b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"387dfc6b\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f1aa285\" data-id=\"7f1aa285\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d6ed045 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7d6ed045\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"bodytext contentText\">\n<p>Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz. Questo progetto globale consentir\u00e0 un processo decisionale unificato, a partire dalla sede europea e passando attraverso le filiali nazionali di Nissan e fino quasi a 1.000 punti vendita per il marchio.<\/p>\n<\/div>\n<div class=\"bodytext contentText\">\n<p>Nissan e autobiz hanno firmato una collaborazione strategica globale. L&#8217;obiettivo del progetto \u00e8 ottimizzare la gestione dei valori residui e degli stock al fine di aumentare la redditivit\u00e0 del marchio e delle sue concessionarie come parte dell&#8217;implementazione della nuova etichetta Nissan Veicoli usati.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24e6eceb elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"24e6eceb\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e2692cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e2692cb\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18144628\" data-id=\"18144628\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42b07380 elementor-widget elementor-widget-heading\" data-id=\"42b07380\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">I big data di autobiz per la rete Nissan<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3310d6bd elementor-widget elementor-widget-text-editor\" data-id=\"3310d6bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il monitoraggio passa per la definizione di indicatori comuni alla rete dei paesi interessati. Questi dati statistici si riferiscono in particolare ai dettagli di ciascuna vettura in stock, vendite, giacenza o ancora di valori di mercato, il tutto applicato a livello di rete e di ogni punto vendita del marchio.<\/p>\n<p>A ci\u00f2 si aggiunge l&#8217;implementazione dello strumento autobizMarket presso le filiali nazionali al fine di consentire ai responsabili dei veicoli usati di gestire le politiche di prezzi e degli stock della rete. Questa collaborazione si estende inizialmente a Germania, Regno Unito, Francia, Italia, Spagna e Portogallo. In totale, i dati di quasi 1.000 punti vendita saranno disponibili per l&#8217;analisi in questi 6 paesi.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dad1538 elementor-widget elementor-widget-heading\" data-id=\"1dad1538\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Una collaborazione di fiducia<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-70e4edf8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70e4edf8\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-17b5d5a8\" data-id=\"17b5d5a8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7271e6b1 elementor-widget elementor-widget-image\" data-id=\"7271e6b1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1504\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5154ea72\" data-id=\"5154ea72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-629eb7b6 elementor-widget elementor-widget-text-editor\" data-id=\"629eb7b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per Jean Philippe Roux, Divisional Sales General Manager Nissan Automotive Europe,<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cb1f413 elementor-widget elementor-widget-text-editor\" data-id=\"2cb1f413\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nell&#8217;ambito dell&#8217;implementazione della nostra nuova etichetta per veicoli usati, Nissan Intelligent Choice, era essenziale mettere in atto strumenti agili e digitali per gestire le prestazioni dei nostri veicoli usati e supportare i nostri concessionari nell&#8217;ottimizzazione del loro rendimento. La collaborazione sviluppata con autobiz \u00e8 di alta qualit\u00e0 e siamo felici di poter gestire il cambiamento con la loro collaborazione.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-114b291 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"114b291\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7698386\" data-id=\"7698386\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eda5b51 elementor-widget elementor-widget-image\" data-id=\"eda5b51\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1504\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d0dbaa9\" data-id=\"d0dbaa9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-826e3f5 elementor-widget elementor-widget-text-editor\" data-id=\"826e3f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo onorati da questa prova di fiducia di Nissan Europe. Questa collaborazione \u00e8 il risultato del lavoro straordinario che i nostri team di progetto e dati hanno svolto insieme ai corrispondenti di Nissan. Ci\u00f2 rafforza la nostra convinzione che una gestione basata sui dati continuer\u00e0 ad affermarsi come lo standard della strategia dell\u2019usato dei pi\u00f9 grandi attori del remarketing in Europa.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe438b8 elementor-widget elementor-widget-text-editor\" data-id=\"fe438b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>aggiunge Emmanuel Labi, Direttore Generale di autobiz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72760077 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72760077\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73e26365\" data-id=\"73e26365\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14f595e2 elementor-widget elementor-widget-shortcode\" data-id=\"14f595e2\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4208\" class=\"elementor elementor-4208 elementor-2712 elementor-2712\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8faa43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8faa43\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d56921c\" data-id=\"d56921c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f76613 elementor-widget elementor-widget-heading\" data-id=\"3f76613\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">A proposito di autobiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbc700 elementor-widget elementor-widget-text-editor\" data-id=\"2bbc700\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 2004, autobiz supporta tutti gli attori europei dell&#8217;industria automobilistica con soluzioni di valutazione e permuta. Questo supporto si basa su 20 anni di cronologia dei dati, sul know-how web, sul software e sull&#8217;esperienza dei 280 dipendenti dell&#8217;azienda. autobiz \u00e8 basata a La D\u00e9fense (Parigi) e ha anche uffici a Berlino, Valencia (Spagna) e Milano. L\u2019azienda supporta pi\u00f9 di 20 leader nel mercato dell&#8217;usato (costruttori, banche, aziende di leasing, case d\u2019asta\u2026) e 5.000 punti vendita in 22 paesi in tutta Europa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e866364 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e866364\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5a5277\" data-id=\"e5a5277\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-024f141 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"024f141\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e51e963 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e51e963\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9a263e\" data-id=\"e9a263e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8f7976 elementor-widget elementor-widget-heading\" data-id=\"b8f7976\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Leggi anche...<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40755c2 communique-carousel overflow-h elementor-widget elementor-widget-jet-posts\" data-id=\"40755c2\" data-element_type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3,&quot;slides_to_scroll&quot;:&quot;1&quot;}\" data-widget_type=\"jet-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-posts jet-elements\"><div class=\"jet-carousel elementor-slick-slider\" data-slider_options=\"{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;.jet-posts__prev-arrow-40755c2&quot;,&quot;nextArrow&quot;:&quot;.jet-posts__next-arrow-40755c2&quot;,&quot;rtl&quot;:false}\" dir=\"ltr\"><div class=\"jet-posts col-row  jet-equal-cols\"><div class=\"jet-posts__prev-arrow-40755c2 jet-arrow prev-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><\/div><div class=\"jet-posts__next-arrow-40755c2 jet-arrow next-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><\/div><div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-introduce-un-nuovo-approccio-basato-sul-mercato-alla-valutazione-b2b-dei-veicoli\/\" target=\"\">autobiz introduce un nuovo approccio basato sul mercato alla valutazione B2B dei veicoli<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/06\/29\/\"  class=\"post__date-link\" ><time datetime=\"2026-06-29T12:41:59+02:00\" title=\"2026-06-29T12:41:59+02:00\">29 Giugno 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">In un mercato dell\u2019usato sempre pi\u00f9 influenzato da improvvise variazioni dei valori B2B,tensioni geopolitiche e cambiamenti rapidi della domanda, gli&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-introduce-un-nuovo-approccio-basato-sul-mercato-alla-valutazione-b2b-dei-veicoli\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/trasparenza-che-genera-fiducia-il-nuovo-standard-per-le-valutazioni-dellusato\/\" target=\"\">Trasparenza che genera fiducia - il nuovo standard per le valutazioni dell\u2019usato<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/05\/29\/\"  class=\"post__date-link\" ><time datetime=\"2026-05-29T12:40:51+02:00\" title=\"2026-05-29T12:40:51+02:00\">29 Maggio 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">In un mercato automotive sempre pi\u00f9 competitivo e guidato dalla fiducia del consumatore, il tema della trasparenza sta assumendo un&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/trasparenza-che-genera-fiducia-il-nuovo-standard-per-le-valutazioni-dellusato\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/point-s-chooses-autobizmarket-to-equip-its-entire-car-sales-network-it\/\" target=\"\">Point S sceglie autobizMarket per dotare la propria rete di vendita auto<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/04\/20\/\"  class=\"post__date-link\" ><time datetime=\"2026-04-20T17:01:24+02:00\" title=\"2026-04-20T17:01:24+02:00\">20 Aprile 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz, leader europeo nella valutazione di veicoli e nelle soluzioni basate sui dati per i professionisti del settore, annuncia la&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/point-s-chooses-autobizmarket-to-equip-its-entire-car-sales-network-it\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-e-jato-dynamics-stringono-una-partnership-strategica-europea-per-ridefinire-gli-standard-di-identificazione-e-valutazione-dei-veicoli\/\" target=\"\">autobiz e JATO Dynamics stringono una partnership strategica europea per ridefinire gli standard di identificazione e valutazione dei veicoli.<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/03\/26\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-26T10:00:54+01:00\" title=\"2026-03-26T10:00:54+01:00\">26 Marzo 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz &#8211; leader europeo nella valutazione dei veicoli usati e nell\u2019analisi sul valore residuo &#8211; e JATO Dynamics &#8211; leader&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-e-jato-dynamics-stringono-una-partnership-strategica-europea-per-ridefinire-gli-standard-di-identificazione-e-valutazione-dei-veicoli\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-italia-premiata-da-great-place-to-work-italia-come-best-workplace-2026\/\" target=\"\">autobiz Italia \u00e8 stata premiata da Great Place To Work\u00ae Italia come una delle migliori aziende italiane per cui lavorare, all\u2019interno della Classifica Best Workplaces\u2122 2026<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/03\/25\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-25T10:21:55+01:00\" title=\"2026-03-25T10:21:55+01:00\">25 Marzo 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz Italia \u00e8 stata valutata dai collaboratori dell\u2019azienda attraverso un\u2019indagine sul clima interno. Il risultato: grande soddisfazione da parte dei&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/autobiz-italia-premiata-da-great-place-to-work-italia-come-best-workplace-2026\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nuova-versione-di-autobizmarket-lanciata-in-italia\/\" target=\"\">La nuova versione di autobizMarket \u00e8 stata lanciata in Italia con un'interfaccia riprogettata e nuove funzionalit\u00e0<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/it\/2026\/03\/12\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-12T08:00:04+01:00\" title=\"2026-03-12T08:00:04+01:00\">12 Marzo 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz annuncia il lancio della nuova versione di autobizMarket, la soluzione di punta per la valutazione dei veicoli usati all\u2019interno&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nuova-versione-di-autobizmarket-lanciata-in-italia\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">Per saperne di pi\u00f9<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bde37e8 elementor-align-center elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"bde37e8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corporate.autobiz.com\/it\/comunicati\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tutti i nostri comunicati<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz. Questo progetto globale consentir\u00e0 un processo decisionale unificato, a partire dalla sede europea e passando attraverso le filiali nazionali di Nissan e fino quasi a 1.000 punti vendita per il marchio.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[59],"tags":[],"class_list":["post-5770","post","type-post","status-publish","format-standard","hentry","category-comunicato-stampa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nissan e autobiz firmano una collaborazione inedita a livello europeo<\/title>\n<meta name=\"description\" content=\"Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nissan e autobiz firmano una collaborazione inedita a livello europeo\" \/>\n<meta property=\"og:description\" content=\"Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/\" \/>\n<meta property=\"og:site_name\" content=\"autobiz Corporate\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-09T15:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-16T10:07:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" \/>\n<meta name=\"author\" content=\"solene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"solene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/\"},\"author\":{\"name\":\"solene\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\"},\"headline\":\"Nissan e autobiz firmano una collaborazione inedita a livello europeo\",\"datePublished\":\"2020-12-09T15:44:00+00:00\",\"dateModified\":\"2022-11-16T10:07:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/\"},\"wordCount\":367,\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"articleSection\":[\"Comunicato stampa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/\",\"name\":\"Nissan e autobiz firmano una collaborazione inedita a livello europeo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"datePublished\":\"2020-12-09T15:44:00+00:00\",\"dateModified\":\"2022-11-16T10:07:32+00:00\",\"description\":\"Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/comunicato-stampa\\\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicato stampa\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/category\\\/comunicato-stampa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nissan e autobiz firmano una collaborazione inedita a livello europeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/\",\"name\":\"autobiz Corporate\",\"description\":\"Leader europ\u00e9en de la cotation automobile et de la reprise\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#organization\",\"name\":\"autobiz Corporate\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"width\":320,\"height\":76,\"caption\":\"autobiz Corporate\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/it\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\",\"name\":\"solene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"caption\":\"solene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nissan e autobiz firmano una collaborazione inedita a livello europeo","description":"Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/","og_locale":"it_IT","og_type":"article","og_title":"Nissan e autobiz firmano una collaborazione inedita a livello europeo","og_description":"Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz.","og_url":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/","og_site_name":"autobiz Corporate","article_published_time":"2020-12-09T15:44:00+00:00","article_modified_time":"2022-11-16T10:07:32+00:00","og_image":[{"url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","type":"","width":"","height":""}],"author":"solene","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"solene","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#article","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/"},"author":{"name":"solene","@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6"},"headline":"Nissan e autobiz firmano una collaborazione inedita a livello europeo","datePublished":"2020-12-09T15:44:00+00:00","dateModified":"2022-11-16T10:07:32+00:00","mainEntityOfPage":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/"},"wordCount":367,"publisher":{"@id":"https:\/\/corporate.autobiz.com\/it\/#organization"},"image":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","articleSection":["Comunicato stampa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/","url":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/","name":"Nissan e autobiz firmano una collaborazione inedita a livello europeo","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#primaryimage"},"image":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","datePublished":"2020-12-09T15:44:00+00:00","dateModified":"2022-11-16T10:07:32+00:00","description":"Firmato su un perimetro di 6 paesi europei, questo accordo mira a permettere a Nissan Europe l\u2019utilizzo dei big data di autobiz.","breadcrumb":{"@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#primaryimage","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/corporate.autobiz.com\/it\/comunicato-stampa\/nissan-e-autobiz-firmano-una-collaborazione-inedita-a-livello-europeo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/corporate.autobiz.com\/it\/"},{"@type":"ListItem","position":2,"name":"Comunicato stampa","item":"https:\/\/corporate.autobiz.com\/it\/category\/comunicato-stampa\/"},{"@type":"ListItem","position":3,"name":"Nissan e autobiz firmano una collaborazione inedita a livello europeo"}]},{"@type":"WebSite","@id":"https:\/\/corporate.autobiz.com\/it\/#website","url":"https:\/\/corporate.autobiz.com\/it\/","name":"autobiz Corporate","description":"Leader europ\u00e9en de la cotation automobile et de la reprise","publisher":{"@id":"https:\/\/corporate.autobiz.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporate.autobiz.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/corporate.autobiz.com\/it\/#organization","name":"autobiz Corporate","url":"https:\/\/corporate.autobiz.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","width":320,"height":76,"caption":"autobiz Corporate"},"image":{"@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/corporate.autobiz.com\/it\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6","name":"solene","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","caption":"solene"}}]}},"_links":{"self":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/posts\/5770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/comments?post=5770"}],"version-history":[{"count":0,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/posts\/5770\/revisions"}],"wp:attachment":[{"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/media?parent=5770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/categories?post=5770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/it\/wp-json\/wp\/v2\/tags?post=5770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}