{"id":5632,"date":"2021-01-11T16:40:00","date_gmt":"2021-01-11T15:40:00","guid":{"rendered":"https:\/\/staging-corporate.shakazoola.com\/sin-categorizar\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/"},"modified":"2023-04-06T09:33:20","modified_gmt":"2023-04-06T07:33:20","slug":"monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos","status":"publish","type":"post","link":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/","title":{"rendered":"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5632\" class=\"elementor elementor-5632 elementor-5084\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-719cee19 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"719cee19\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4548c048\" data-id=\"4548c048\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1315372e elementor-widget elementor-widget-breadcrumbs\" data-id=\"1315372e\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/corporate.autobiz.com\/es\/\">Inicio<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38c02145 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38c02145\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b117bdb\" data-id=\"3b117bdb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fcdcb7e elementor-widget elementor-widget-text-editor\" data-id=\"5fcdcb7e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t11 de enero de 2021\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57af4aa9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"57af4aa9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bd1a491 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bd1a491\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55e05f10\" data-id=\"55e05f10\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3715c8d5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3715c8d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz, uno de los l\u00edderes europeos en la tasaci\u00f3n de veh\u00edculos. Este producto es el fruto de la I+D conjunta entre las dos empresas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24e093f7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"24e093f7\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7be0c1ad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7be0c1ad\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cdce56e\" data-id=\"cdce56e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-195b5782 elementor-widget elementor-widget-heading\" data-id=\"195b5782\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">El reconocimiento de da\u00f1os en tu smartphone<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8a760 elementor-widget elementor-widget-text-editor\" data-id=\"2d8a760\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La asociaci\u00f3n entre las dos empresas tecnol\u00f3gicas francesas busca hacer fiable y simplificar el proceso de inspecci\u00f3n de veh\u00edculos, en los casos de compra en un punto de venta o a distancia. A trav\u00e9s de su uni\u00f3n, autobiz y Monk ser\u00e1n de los primeros en poner a disposici\u00f3n de los profesionales la potencia del reconocimiento de da\u00f1os. El objetivo es integrar de la manera m\u00e1s eficaz posible esta tecnolog\u00eda en los programas de compra de autobiz para un uso realmente practico en el d\u00eda a d\u00eda de todos los profesionales del sector de los veh\u00edculos de ocasi\u00f3n. El producto desarrollado funciona con un Smartphone, sin grandes inversiones en instalaciones como en costes fijos.<\/p><p>Durante una compra, el profesional debe enfrentarse a varios problemas: ser r\u00e1pido y eficaz de cara al cliente, recopilar la totalidad de los gastos del veh\u00edculo con precisi\u00f3n para tener controlados los costes de puesta a punto, generar una descripci\u00f3n detallada para vender los veh\u00edculos adquiridos lo m\u00e1s r\u00e1pidamente posible, y, por \u00faltimo, calcular los precios de compra y venta con la mayor seguridad y precisi\u00f3n posible para optimizar sus m\u00e1rgenes.<\/p><p>En un contexto en el que el mercado de ocasi\u00f3n en 2021 estuvo claramente bajo tensi\u00f3n, agilizar el proceso de venta de veh\u00edculos de ocasi\u00f3n \u00fanicamente puede ayudar a sus protagonistas en su b\u00fasqueda de la eficacia, optimizando la relaci\u00f3n tiempo\/cliente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7e128f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e128f6\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6e468d1\" data-id=\"6e468d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-714c0ec elementor-widget elementor-widget-image\" data-id=\"714c0ec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1506\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d48d319\" data-id=\"d48d319\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c31c52c elementor-widget elementor-widget-text-editor\" data-id=\"c31c52c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ya empleamos actualmente la inteligencia artificial para el c\u00e1lculo autom\u00e1tico de los precios de compra, con mucho \u00e9xito. M\u00e1s del 90% de nuestras de decisiones de compra en los puntos de venta se calculan mediante nuestros algoritmos. Tras una peritaci\u00f3n, en tan solo unos instantes, nuestros programas identifican el veh\u00edculo, consideran los costes de puesta a punto, eval\u00faan los riesgos de la compra, determinan el mejor canal de comercializaci\u00f3n y ofrecen un precio garantizado a nuestros socios. A\u00f1adiendo la inteligencia artificial de Monk en nuestro proceso nos va a permitir reducir a\u00fan m\u00e1s el tiempo necesario para una tasaci\u00f3n y homogeneizar el total de los gastos entre los comerciales.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-796708d elementor-widget elementor-widget-text-editor\" data-id=\"796708d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>apunta Emmanuel Labi, Director General de autobiz.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2ee063 elementor-widget elementor-widget-heading\" data-id=\"f2ee063\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Un gran potencial inmediato para los usuarios de m\u00e1s de 4.500 puntos de venta<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dd64fe elementor-widget elementor-widget-text-editor\" data-id=\"8dd64fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A traves de este proyecto de colaboraci\u00f3n, autobiz proporciona a Monk decenas de miles de conjuntos de datos, derivados de sus herramientas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-54dabf35 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"54dabf35\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1dd34b92\" data-id=\"1dd34b92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f68c3f3 elementor-widget elementor-widget-image\" data-id=\"7f68c3f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" class=\"attachment-large size-large wp-image-1506\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fc2cbc6\" data-id=\"fc2cbc6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5010caa5 elementor-widget elementor-widget-text-editor\" data-id=\"5010caa5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estamos muy orgullosos de anunciar esta asociaci\u00f3n con autobiz, un protagonista hist\u00f3rico que pondr\u00e1 la tecnolog\u00eda y la inteligencia artificial de Monk a disposici\u00f3n de miles de concesionarios de autom\u00f3viles. Con esta uni\u00f3n demostramos conjuntamente que el proceso de compra de un veh\u00edculo de ocasi\u00f3n puede realizarse mayoritariamente a distancia gracias a nuestros algoritmos. Este proyecto com\u00fan permitir\u00e1 a numerosos interesados del remarketing de acceder a las herramientas que hemos desarrollado desde hace varios meses. La asociaci\u00f3n de nuestras tasaciones y la profesionalidad de los dirigentes de autobiz son clave para Monk.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b37e7b elementor-widget elementor-widget-text-editor\" data-id=\"6b37e7b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>a\u00f1ade Aboubakr Laraki, cofundador y Director Ejecutivo de Monk.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6920c20e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6920c20e\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e88d2fa\" data-id=\"7e88d2fa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-75fe5556 elementor-widget elementor-widget-shortcode\" data-id=\"75fe5556\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"4210\" class=\"elementor elementor-4210 elementor-2712 elementor-2712\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b8faa43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b8faa43\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d56921c\" data-id=\"d56921c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f76613 elementor-widget elementor-widget-heading\" data-id=\"3f76613\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Sobre autobiz<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bbc700 elementor-widget elementor-widget-text-editor\" data-id=\"2bbc700\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Desde 2004, autobiz acompa\u00f1a a todos los actores de la industria del autom\u00f3vil en Europa con soluciones de tasaci\u00f3n y compraventa. Este acompa\u00f1amiento se basa en 20 a\u00f1os de historia de datos y en los conocimientos web, de software y empresariales de los 280 empleados de la empresa. Hoy en d\u00eda, con sede en La D\u00e9fense (92), autobiz tambi\u00e9n tiene oficinas en Berl\u00edn, Valencia (Espa\u00f1a) y Mil\u00e1n. autobiz presta apoyo a m\u00e1s de 20 l\u00edderes del remarketing de veh\u00edculos de ocasi\u00f3n (fabricantes, bancos, arrendadores, subastadores, etc.), as\u00ed como a 5.000 puntos de venta en 22 pa\u00edses de Europa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e866364 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e866364\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5a5277\" data-id=\"e5a5277\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-024f141 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"024f141\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e51e963 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e51e963\" data-element_type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9a263e\" data-id=\"e9a263e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b8f7976 elementor-widget elementor-widget-heading\" data-id=\"b8f7976\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lea tambi\u00e9n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40755c2 communique-carousel overflow-h elementor-widget elementor-widget-jet-posts\" data-id=\"40755c2\" data-element_type=\"widget\" data-settings=\"{&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;columns&quot;:3,&quot;slides_to_scroll&quot;:&quot;1&quot;}\" data-widget_type=\"jet-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-jet-posts jet-elements\"><div class=\"jet-carousel elementor-slick-slider\" data-slider_options=\"{&quot;autoplaySpeed&quot;:5000,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:500,&quot;arrows&quot;:true,&quot;dots&quot;:false,&quot;slidesToScroll&quot;:1,&quot;prevArrow&quot;:&quot;.jet-posts__prev-arrow-40755c2&quot;,&quot;nextArrow&quot;:&quot;.jet-posts__next-arrow-40755c2&quot;,&quot;rtl&quot;:false}\" dir=\"ltr\"><div class=\"jet-posts col-row  jet-equal-cols\"><div class=\"jet-posts__prev-arrow-40755c2 jet-arrow prev-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-left\"><\/i><\/div><div class=\"jet-posts__next-arrow-40755c2 jet-arrow next-arrow\"><i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i><\/div><div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/autobiz-amplia-sus-operaciones-de-valor-residual-en-iberia\/\" target=\"\">autobiz ampl\u00eda sus operaciones de Valor Residual en Iberia<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/es\/2026\/07\/15\/\"  class=\"post__date-link\" ><time datetime=\"2026-07-15T14:50:03+02:00\" title=\"2026-07-15T14:50:03+02:00\">15 de julio de 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz anuncia la expansi\u00f3n de sus actividades de Valor Residual y soluciones para la Financiaci\u00f3n de veh\u00edculos en la Pen\u00ednsula&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/autobiz-amplia-sus-operaciones-de-valor-residual-en-iberia\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">En savoir plus<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/point-s-elige-a-autobizmarket-para-equipar-toda-su-red-de-venta-de-automoviles\/\" target=\"\">Point S elige a autobizMarket para equipar toda su red de venta de autom\u00f3viles<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/es\/2026\/04\/20\/\"  class=\"post__date-link\" ><time datetime=\"2026-04-20T17:01:24+02:00\" title=\"2026-04-20T17:01:24+02:00\">20 de abril de 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz, l\u00edder europeo en valoraci\u00f3n de autom\u00f3viles y soluciones de datos para profesionales, anuncia la firma de una alianza estrat\u00e9gica&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/point-s-elige-a-autobizmarket-para-equipar-toda-su-red-de-venta-de-automoviles\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">En savoir plus<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/autobiz-and-jato-dynamics-forge-strategic-european-partnership-to-redefine-vehicle-identification-and-valuation-standards\/\" target=\"\">autobiz y JATO Dynamics forjan una alianza estrat\u00e9gica europea para redefinir los est\u00e1ndares de identificaci\u00f3n y valoraci\u00f3n de veh\u00edculos<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/es\/2026\/03\/31\/\"  class=\"post__date-link\" ><time datetime=\"2026-03-31T10:05:25+02:00\" title=\"2026-03-31T10:05:25+02:00\">31 de marzo de 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz, l\u00edder europeo en valoraci\u00f3n de veh\u00edculos usados \u200b\u200be informaci\u00f3n sobre su valor residual, y JATO Dynamics, l\u00edder mundial en&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/autobiz-and-jato-dynamics-forge-strategic-european-partnership-to-redefine-vehicle-identification-and-valuation-standards\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">En savoir plus<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/la-nueva-version-de-autobizsistemavo-se-lanza-en-espana-con-una-interfaz-redisenada-y-uncionalidades-especificas-para-el-mercado\/\" target=\"\">La nueva versi\u00f3n de autobizSistemaVO se lanza en Espa\u00f1a con una interfaz redise\u00f1ada y uncionalidades espec\u00edficas para el mercado<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/es\/2026\/02\/11\/\"  class=\"post__date-link\" ><time datetime=\"2026-02-11T17:03:32+01:00\" title=\"2026-02-11T17:03:32+01:00\">11 de febrero de 2026<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz anuncia el despliegue de la nueva versi\u00f3n de autobizSistemaVO, la versi\u00f3n espa\u00f1ola de autobizMarket, una de las soluciones emblem\u00e1ticas&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/la-nueva-version-de-autobizsistemavo-se-lanza-en-espana-con-una-interfaz-redisenada-y-uncionalidades-especificas-para-el-mercado\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">En savoir plus<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/firma-de-consultoria-del-ano-autobiz-fue-galardonada-por-autobiznext-la-solucion-que-redefine-la-gestion-del-valor-residual-en-europa\/\" target=\"\">Firma de consultor\u00eda del a\u00f1o: autobiz fue galardonada por autobiznext, la soluci\u00f3n que redefine la gesti\u00f3n del valor residual en europa<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/es\/2025\/11\/12\/\"  class=\"post__date-link\" ><time datetime=\"2025-11-12T13:45:51+01:00\" title=\"2025-11-12T13:45:51+01:00\">12 de noviembre de 2025<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz fue galardonada con el t\u00edtulo de \u201cFirma de Consultor\u00eda del A\u00f1o\u201d en los Premios GlobalData Automotive Europe 2025 en&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/firma-de-consultoria-del-ano-autobiz-fue-galardonada-por-autobiznext-la-solucion-que-redefine-la-gestion-del-valor-residual-en-europa\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">En savoir plus<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<div class=\"jet-posts__item\">\n\t<div class=\"jet-posts__inner-box\"><div class=\"jet-posts__inner-content\"><h4 class=\"entry-title\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/en-cours-de-test-avance-chez-stellantis-carcheck-ai-promet-de-faire-gagner-jusqua-3-semaines-lors-du-defleet-dun-vehicule-2\/\" target=\"\">Actualmente en la fase final con Stellantis, Carcheck.ai promete ahorrar hasta 3 semanas durante el proceso de defleet de un veh\u00edculo<\/a><\/h4><div class=\"post-meta\"><span class=\"post__date post-meta__item\"><a href=\"https:\/\/corporate.autobiz.com\/es\/2025\/10\/21\/\"  class=\"post__date-link\" ><time datetime=\"2025-10-21T09:00:00+02:00\" title=\"2025-10-21T09:00:00+02:00\">21 de octubre de 2025<\/time><\/a><\/span><\/div><div class=\"entry-excerpt\">autobiz da un nuevo paso adelante en la automatizaci\u00f3n de las tasaciones y la digitalizaci\u00f3n del remarketing. Basada en la&hellip;<\/div><div class=\"jet-more-wrap\"><a href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/en-cours-de-test-avance-chez-stellantis-carcheck-ai-promet-de-faire-gagner-jusqua-3-semaines-lors-du-defleet-dun-vehicule-2\/\" class=\"btn btn-primary elementor-button elementor-size-md jet-more\" target=\"\"><span class=\"btn__text\">En savoir plus<\/span><span class=\"jet-elements-icon jet-more-icon\"><i aria-hidden=\"true\" class=\"fas fa-caret-right\"><\/i><\/span><\/a><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bde37e8 elementor-align-center elementor-widget-mobile__width-initial elementor-widget elementor-widget-button\" data-id=\"bde37e8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/corporate.autobiz.com\/nos-actualites\/nos-communiques\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Todos nuestros bar\u00f3metros<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz, uno de los l\u00edderes europeos de la tasaci\u00f3n de veh\u00edculos. Este producto es el fruto de la I+D conjunta entre las dos empresas.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[57],"tags":[],"class_list":["post-5632","post","type-post","status-publish","format-standard","hentry","category-comunicado-de-prensa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os<\/title>\n<meta name=\"description\" content=\"Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os\" \/>\n<meta property=\"og:description\" content=\"Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/\" \/>\n<meta property=\"og:site_name\" content=\"autobiz Corporate\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-11T15:40:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-06T07:33:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg\" \/>\n<meta name=\"author\" content=\"solene\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"solene\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/\"},\"author\":{\"name\":\"solene\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\"},\"headline\":\"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os\",\"datePublished\":\"2021-01-11T15:40:00+00:00\",\"dateModified\":\"2023-04-06T07:33:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/\"},\"wordCount\":608,\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"articleSection\":[\"Comunicado de prensa\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/\",\"name\":\"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"datePublished\":\"2021-01-11T15:40:00+00:00\",\"dateModified\":\"2023-04-06T07:33:20+00:00\",\"description\":\"Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/testi.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/comunicado-de-prensa\\\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de prensa\",\"item\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/category\\\/comunicado-de-prensa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/\",\"name\":\"autobiz Corporate\",\"description\":\"Leader europ\u00e9en de la cotation automobile et de la reprise\",\"publisher\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#organization\",\"name\":\"autobiz Corporate\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"contentUrl\":\"https:\\\/\\\/corporate.autobiz.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/logo-autobiz.png\",\"width\":320,\"height\":76,\"caption\":\"autobiz Corporate\"},\"image\":{\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/corporate.autobiz.com\\\/es\\\/#\\\/schema\\\/person\\\/9ae4aeeb57b606ec639da21578da0ae6\",\"name\":\"solene\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g\",\"caption\":\"solene\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os","description":"Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/","og_locale":"es_ES","og_type":"article","og_title":"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os","og_description":"Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz.","og_url":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/","og_site_name":"autobiz Corporate","article_published_time":"2021-01-11T15:40:00+00:00","article_modified_time":"2023-04-06T07:33:20+00:00","og_image":[{"url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","type":"","width":"","height":""}],"author":"solene","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"solene","Tiempo de lectura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#article","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/"},"author":{"name":"solene","@id":"https:\/\/corporate.autobiz.com\/es\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6"},"headline":"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os","datePublished":"2021-01-11T15:40:00+00:00","dateModified":"2023-04-06T07:33:20+00:00","mainEntityOfPage":{"@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/"},"wordCount":608,"publisher":{"@id":"https:\/\/corporate.autobiz.com\/es\/#organization"},"image":{"@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","articleSection":["Comunicado de prensa"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/","url":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/","name":"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os","isPartOf":{"@id":"https:\/\/corporate.autobiz.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#primaryimage"},"image":{"@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#primaryimage"},"thumbnailUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","datePublished":"2021-01-11T15:40:00+00:00","dateModified":"2023-04-06T07:33:20+00:00","description":"Este acuerdo tiene como objetivo unir la avanzada tecnolog\u00eda de reconocimiento de da\u00f1os mediante im\u00e1genes de la start-up francesa Monk, a la experiencia de autobiz.","breadcrumb":{"@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#primaryimage","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/testi.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/corporate.autobiz.com\/es\/comunicado-de-prensa\/monk-y-autobiz-firman-una-asociacion-para-el-reconocimiento-de-danos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/corporate.autobiz.com\/es\/"},{"@type":"ListItem","position":2,"name":"Comunicado de prensa","item":"https:\/\/corporate.autobiz.com\/es\/category\/comunicado-de-prensa\/"},{"@type":"ListItem","position":3,"name":"Monk y autobiz firman una asociaci\u00f3n para el reconocimiento de da\u00f1os"}]},{"@type":"WebSite","@id":"https:\/\/corporate.autobiz.com\/es\/#website","url":"https:\/\/corporate.autobiz.com\/es\/","name":"autobiz Corporate","description":"Leader europ\u00e9en de la cotation automobile et de la reprise","publisher":{"@id":"https:\/\/corporate.autobiz.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/corporate.autobiz.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/corporate.autobiz.com\/es\/#organization","name":"autobiz Corporate","url":"https:\/\/corporate.autobiz.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/corporate.autobiz.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","contentUrl":"https:\/\/corporate.autobiz.com\/wp-content\/uploads\/2022\/07\/logo-autobiz.png","width":320,"height":76,"caption":"autobiz Corporate"},"image":{"@id":"https:\/\/corporate.autobiz.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/corporate.autobiz.com\/es\/#\/schema\/person\/9ae4aeeb57b606ec639da21578da0ae6","name":"solene","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8d51eb61b9ec15233721a8008decd5047bf06b8e454fb4c7fb3435f71edd3303?s=96&d=mm&r=g","caption":"solene"}}]}},"_links":{"self":[{"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/posts\/5632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/comments?post=5632"}],"version-history":[{"count":0,"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/posts\/5632\/revisions"}],"wp:attachment":[{"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/media?parent=5632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/categories?post=5632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/corporate.autobiz.com\/es\/wp-json\/wp\/v2\/tags?post=5632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}